{"id":142,"name":"Atziri Hern\u00e1ndez","url":"http:\/\/www.infosecurity.com.mx","description":"INFOSECURITY\r\nwww.infosecurity.com.mx","link":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/","slug":"atzirihernandez","avatar_urls":{"24":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg","48":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg","96":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atziri Hern\u00e1ndez<\/title>\n<meta name=\"description\" content=\"INFOSECURITY www.infosecurity.com.mx\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Atziri Hern\u00e1ndez\" \/>\n<meta property=\"og:description\" content=\"INFOSECURITY www.infosecurity.com.mx\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/\" \/>\n<meta property=\"og:site_name\" content=\"Entorno Empresarial\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"796\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comcoparmex\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/atzirihernandez\\\/\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/atzirihernandez\\\/\",\"name\":\"Atziri Hern\u00e1ndez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#website\"},\"description\":\"INFOSECURITY www.infosecurity.com.mx\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/atzirihernandez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/atzirihernandez\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/atzirihernandez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivos para Atziri Hern\u00e1ndez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#website\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\",\"name\":\"Revista Entorno Empresarial\",\"description\":\"Coparmex Jalisco\",\"publisher\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#organization\",\"name\":\"Coparmex Jalisco\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-amp.png\",\"contentUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-amp.png\",\"width\":120,\"height\":90,\"caption\":\"Coparmex Jalisco\"},\"image\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/comcoparmex\",\"https:\\\/\\\/x.com\\\/comcoparmex\",\"http:\\\/\\\/instagram.com\\\/coparmexjalisco\",\"https:\\\/\\\/mx.linkedin.com\\\/company\\\/coparmex-jalisco\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CoparmexJaliscomx\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/person\\\/f99087a2cb94d9d54a867f6790ba9ace\",\"name\":\"Atziri Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg\",\"caption\":\"Atziri Hern\u00e1ndez\"},\"description\":\"INFOSECURITY www.infosecurity.com.mx\",\"sameAs\":[\"http:\\\/\\\/www.infosecurity.com.mx\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/atzirihernandez\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atziri Hern\u00e1ndez","description":"INFOSECURITY www.infosecurity.com.mx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/","og_locale":"es_MX","og_type":"profile","og_title":"Atziri Hern\u00e1ndez","og_description":"INFOSECURITY www.infosecurity.com.mx","og_url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/","og_site_name":"Entorno Empresarial","og_image":[{"width":796,"height":800,"url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comcoparmex","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/","name":"Atziri Hern\u00e1ndez","isPartOf":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#website"},"description":"INFOSECURITY www.infosecurity.com.mx","breadcrumb":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/"},{"@type":"ListItem","position":2,"name":"Archivos para Atziri Hern\u00e1ndez"}]},{"@type":"WebSite","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#website","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/","name":"Revista Entorno Empresarial","description":"Coparmex Jalisco","publisher":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#organization","name":"Coparmex Jalisco","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/logo\/image\/","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/02\/logo-amp.png","contentUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/02\/logo-amp.png","width":120,"height":90,"caption":"Coparmex Jalisco"},"image":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/comcoparmex","https:\/\/x.com\/comcoparmex","http:\/\/instagram.com\/coparmexjalisco","https:\/\/mx.linkedin.com\/company\/coparmex-jalisco","https:\/\/www.youtube.com\/c\/CoparmexJaliscomx"]},{"@type":"Person","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/person\/f99087a2cb94d9d54a867f6790ba9ace","name":"Atziri Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg","contentUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/11\/Captura-de-pantalla-2024-11-08-151704-150x150.jpg","caption":"Atziri Hern\u00e1ndez"},"description":"INFOSECURITY www.infosecurity.com.mx","sameAs":["http:\/\/www.infosecurity.com.mx"],"mainEntityOfPage":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/atzirihernandez\/"}}]}},"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/users\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/users"}]}}