{"id":132,"name":"Mar\u00eda Rosas Palacios","url":"","description":"","link":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/","slug":"mariarosaspalacios","avatar_urls":{"24":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios-150x150.jpg","48":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios-150x150.jpg","96":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios-150x150.jpg"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mar\u00eda Rosas Palacios, Autor Entorno Empresarial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Mar\u00eda Rosas Palacios, Autor Entorno Empresarial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/\" \/>\n<meta property=\"og:site_name\" content=\"Entorno Empresarial\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"419\" \/>\n\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comcoparmex\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/mariarosaspalacios\\\/\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/mariarosaspalacios\\\/\",\"name\":\"Mar\u00eda Rosas Palacios, Autor Entorno Empresarial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/mariarosaspalacios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/mariarosaspalacios\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/mariarosaspalacios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivos para Mar\u00eda Rosas Palacios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#website\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\",\"name\":\"Revista Entorno Empresarial\",\"description\":\"Coparmex Jalisco\",\"publisher\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#organization\",\"name\":\"Coparmex Jalisco\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-amp.png\",\"contentUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-amp.png\",\"width\":120,\"height\":90,\"caption\":\"Coparmex Jalisco\"},\"image\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/comcoparmex\",\"https:\\\/\\\/x.com\\\/comcoparmex\",\"http:\\\/\\\/instagram.com\\\/coparmexjalisco\",\"https:\\\/\\\/mx.linkedin.com\\\/company\\\/coparmex-jalisco\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CoparmexJaliscomx\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/person\\\/25d23957527e6a981a186b4b8ac60d6d\",\"name\":\"Mar\u00eda Rosas Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Maria-Rosas-Palacios-150x150.jpg\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Maria-Rosas-Palacios-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Maria-Rosas-Palacios-150x150.jpg\",\"caption\":\"Mar\u00eda Rosas Palacios\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/mariarosaspalacios\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00eda Rosas Palacios, Autor Entorno Empresarial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/","og_locale":"es_MX","og_type":"profile","og_title":"Mar\u00eda Rosas Palacios, Autor Entorno Empresarial","og_url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/","og_site_name":"Entorno Empresarial","og_image":[{"width":419,"height":509,"url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comcoparmex","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/","name":"Mar\u00eda Rosas Palacios, Autor Entorno Empresarial","isPartOf":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#website"},"breadcrumb":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/"},{"@type":"ListItem","position":2,"name":"Archivos para Mar\u00eda Rosas Palacios"}]},{"@type":"WebSite","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#website","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/","name":"Revista Entorno Empresarial","description":"Coparmex Jalisco","publisher":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#organization","name":"Coparmex Jalisco","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/logo\/image\/","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/02\/logo-amp.png","contentUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/02\/logo-amp.png","width":120,"height":90,"caption":"Coparmex Jalisco"},"image":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/comcoparmex","https:\/\/x.com\/comcoparmex","http:\/\/instagram.com\/coparmexjalisco","https:\/\/mx.linkedin.com\/company\/coparmex-jalisco","https:\/\/www.youtube.com\/c\/CoparmexJaliscomx"]},{"@type":"Person","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/person\/25d23957527e6a981a186b4b8ac60d6d","name":"Mar\u00eda Rosas Palacios","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios-150x150.jpg","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios-150x150.jpg","contentUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/03\/Maria-Rosas-Palacios-150x150.jpg","caption":"Mar\u00eda Rosas Palacios"},"mainEntityOfPage":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/mariarosaspalacios\/"}}]}},"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/users\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/users"}]}}