{"id":7470,"date":"2024-08-29T21:02:00","date_gmt":"2024-08-30T03:02:00","guid":{"rendered":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/?p=7470"},"modified":"2024-10-14T12:14:33","modified_gmt":"2024-10-14T18:14:33","slug":"conexion-talento-2024","status":"publish","type":"post","link":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/","title":{"rendered":"Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024"},"content":{"rendered":"\n<p>Esta tarde dio inicio <em>Conexi\u00f3n de Talento <\/em>Coparmex Jalisco <em>2024<\/em>, evento enfocado en la transformaci\u00f3n del capital humano y la innovaci\u00f3n en el \u00e1mbito laboral, que reuni\u00f3 a expertos en recursos humanos, l\u00edderes empresariales y de opini\u00f3n para abordar los desaf\u00edos actuales y las oportunidades que definen el entorno laboral.<\/p>\n\n\n\n<p>Este a\u00f1o <em>Conexi\u00f3n de Talento <\/em>dise\u00f1\u00f3 una agenda centrada en el bienestar y la felicidad de las y los colaboradores, enfoque que no solo responde a las nuevas exigencias del mercado laboral, sino que tambi\u00e9n busca equipar a los expertos en recursos humanos y l\u00edderes empresariales con las herramientas necesarias para enfrentar los retos de la actualidad y las tendencias del futuro.<\/p>\n\n\n\n<p>Entre las tem\u00e1ticas abordadas durante las conferencias, destacaron: <em>Organizaciones Conscientes<\/em>, <em>Prop\u00f3sito de Vida Trascendiendo la Inteligencia Artificial<\/em>, <em>Cultura Organizacional como Impulsor de la Felicidad<\/em>, <em>De Jefe a L\u00edder<\/em>, <em>Del An\u00e1lisis de Datos a la Felicidad, Competencias Gallup, Tecnolog\u00edas para la Gesti\u00f3n del Talento y el Desempe\u00f1o<\/em>, y <em>Bienestar y Felicidad<\/em>. Estos temas subrayan la importancia de construir una cultura organizacional s\u00f3lida a trav\u00e9s del modelamiento, la comunicaci\u00f3n efectiva y la consistencia en las consecuencias.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_29331-1024x683.jpg\" alt=\"\" class=\"wp-image-7474\" style=\"width:449px;height:auto\" srcset=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_29331-1024x683.jpg 1024w, https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_29331-300x200.jpg 300w, https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_29331-768x512.jpg 768w, https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_29331.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>En su intervenci\u00f3n, diversos expertos coincidieron en que los l\u00edderes actuales deben priorizar la seguridad psicol\u00f3gica, fomentar la innovaci\u00f3n, promover h\u00e1bitos saludables y compartir las reflexiones detr\u00e1s de cada decisi\u00f3n. Adem\u00e1s, se destac\u00f3 la necesidad de adaptarse a las nuevas tecnolog\u00edas para incrementar la productividad y fidelizar al talento clave.<em>Conexi\u00f3n de Talento 2024<\/em> cierra con una firme convicci\u00f3n: el futuro del trabajo depende de la capacidad de las organizaciones para innovar, adaptarse y priorizar el bienestar de su gente. En Coparmex Jalisco, seguimos comprometidos en liderar este cambio y en apoyar a las empresas en la construcci\u00f3n de un entorno laboral m\u00e1s humano, productivo y feliz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta tarde dio inicio Conexi\u00f3n de Talento Coparmex Jalisco 2024, evento enfocado en la transformaci\u00f3n del capital humano y la innovaci\u00f3n en el \u00e1mbito laboral,<\/p>\n","protected":false},"author":2,"featured_media":7471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158,152],"tags":[1430,1431,405,1433,1432,1429,215,649],"class_list":["post-7470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capital-humano","category-empresas","tag-capitalhumano","tag-conexiondetalento2024","tag-coparmex-jalisco","tag-coparmexjalisco","tag-culturaorganizacional","tag-innovacionlaboral","tag-liderazgo","tag-recursoshumanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liderazgo e Innovaci\u00f3n en Conexi\u00f3n de Talento 2024<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liderazgo e Innovaci\u00f3n en Conexi\u00f3n de Talento 2024\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Entorno Empresarial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/comcoparmex\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T03:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T18:14:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_91271.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1423\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coparmex Jalisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comcoparmex\" \/>\n<meta name=\"twitter:site\" content=\"@comcoparmex\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coparmex Jalisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/\"},\"author\":{\"name\":\"Coparmex Jalisco\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/person\\\/7d1d56a9587bfb3a725cd3dbfbdb9d44\"},\"headline\":\"Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024\",\"datePublished\":\"2024-08-30T03:02:00+00:00\",\"dateModified\":\"2024-10-14T18:14:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/\"},\"wordCount\":341,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMG_91271.jpg\",\"keywords\":[\"CapitalHumano\",\"Conexi\u00f3nDeTalento2024\",\"coparmex jalisco\",\"CoparmexJalisco\",\"CulturaOrganizacional\",\"Innovaci\u00f3nLaboral\",\"liderazgo\",\"recursoshumanos\"],\"articleSection\":[\"Capital Humano\",\"Empresas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/\",\"name\":\"Liderazgo e Innovaci\u00f3n en Conexi\u00f3n de Talento 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMG_91271.jpg\",\"datePublished\":\"2024-08-30T03:02:00+00:00\",\"dateModified\":\"2024-10-14T18:14:33+00:00\",\"description\":\"Descubre c\u00f3mo Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMG_91271.jpg\",\"contentUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMG_91271.jpg\",\"width\":1423,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/conexion-talento-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#website\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\",\"name\":\"Revista Entorno Empresarial\",\"description\":\"Coparmex Jalisco\",\"publisher\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#organization\",\"name\":\"Coparmex Jalisco\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-amp.png\",\"contentUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-amp.png\",\"width\":120,\"height\":90,\"caption\":\"Coparmex Jalisco\"},\"image\":{\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/comcoparmex\",\"https:\\\/\\\/x.com\\\/comcoparmex\",\"http:\\\/\\\/instagram.com\\\/coparmexjalisco\",\"https:\\\/\\\/mx.linkedin.com\\\/company\\\/coparmex-jalisco\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CoparmexJaliscomx\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/#\\\/schema\\\/person\\\/7d1d56a9587bfb3a725cd3dbfbdb9d44\",\"name\":\"Coparmex Jalisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/favicon-150x133.png\",\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/favicon-150x133.png\",\"contentUrl\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/favicon-150x133.png\",\"caption\":\"Coparmex Jalisco\"},\"url\":\"https:\\\/\\\/coparmexjal.org.mx\\\/entorno-empresarial\\\/author\\\/coparmexjalisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liderazgo e Innovaci\u00f3n en Conexi\u00f3n de Talento 2024","description":"Descubre c\u00f3mo Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/","og_locale":"es_MX","og_type":"article","og_title":"Liderazgo e Innovaci\u00f3n en Conexi\u00f3n de Talento 2024","og_description":"Descubre c\u00f3mo Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024.","og_url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/","og_site_name":"Entorno Empresarial","article_publisher":"https:\/\/facebook.com\/comcoparmex","article_published_time":"2024-08-30T03:02:00+00:00","article_modified_time":"2024-10-14T18:14:33+00:00","og_image":[{"width":1423,"height":800,"url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_91271.jpg","type":"image\/jpeg"}],"author":"Coparmex Jalisco","twitter_card":"summary_large_image","twitter_creator":"@comcoparmex","twitter_site":"@comcoparmex","twitter_misc":{"Escrito por":"Coparmex Jalisco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#article","isPartOf":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/"},"author":{"name":"Coparmex Jalisco","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/person\/7d1d56a9587bfb3a725cd3dbfbdb9d44"},"headline":"Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024","datePublished":"2024-08-30T03:02:00+00:00","dateModified":"2024-10-14T18:14:33+00:00","mainEntityOfPage":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/"},"wordCount":341,"commentCount":0,"publisher":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#organization"},"image":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_91271.jpg","keywords":["CapitalHumano","Conexi\u00f3nDeTalento2024","coparmex jalisco","CoparmexJalisco","CulturaOrganizacional","Innovaci\u00f3nLaboral","liderazgo","recursoshumanos"],"articleSection":["Capital Humano","Empresas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/","name":"Liderazgo e Innovaci\u00f3n en Conexi\u00f3n de Talento 2024","isPartOf":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#primaryimage"},"image":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_91271.jpg","datePublished":"2024-08-30T03:02:00+00:00","dateModified":"2024-10-14T18:14:33+00:00","description":"Descubre c\u00f3mo Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024.","breadcrumb":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#primaryimage","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_91271.jpg","contentUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2024\/08\/IMG_91271.jpg","width":1423,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/conexion-talento-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/"},{"@type":"ListItem","position":2,"name":"Coparmex Jalisco impulsa la innovaci\u00f3n y el desarrollo del capital humano en Conexi\u00f3n de Talento 2024"}]},{"@type":"WebSite","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#website","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/","name":"Revista Entorno Empresarial","description":"Coparmex Jalisco","publisher":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#organization","name":"Coparmex Jalisco","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/logo\/image\/","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/02\/logo-amp.png","contentUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/02\/logo-amp.png","width":120,"height":90,"caption":"Coparmex Jalisco"},"image":{"@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/comcoparmex","https:\/\/x.com\/comcoparmex","http:\/\/instagram.com\/coparmexjalisco","https:\/\/mx.linkedin.com\/company\/coparmex-jalisco","https:\/\/www.youtube.com\/c\/CoparmexJaliscomx"]},{"@type":"Person","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/#\/schema\/person\/7d1d56a9587bfb3a725cd3dbfbdb9d44","name":"Coparmex Jalisco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/06\/favicon-150x133.png","url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/06\/favicon-150x133.png","contentUrl":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-content\/uploads\/2020\/06\/favicon-150x133.png","caption":"Coparmex Jalisco"},"url":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/author\/coparmexjalisco\/"}]}},"_links":{"self":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/posts\/7470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/comments?post=7470"}],"version-history":[{"count":3,"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/posts\/7470\/revisions"}],"predecessor-version":[{"id":7476,"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/posts\/7470\/revisions\/7476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/media\/7471"}],"wp:attachment":[{"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/media?parent=7470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/categories?post=7470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/entorno-empresarial\/wp-json\/wp\/v2\/tags?post=7470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}