{"id":23979,"date":"2025-02-02T13:39:14","date_gmt":"2025-02-02T19:39:14","guid":{"rendered":"https:\/\/coparmexjal.org.mx\/cpx\/?post_type=mec-events&#038;p=23979"},"modified":"2025-07-01T12:26:06","modified_gmt":"2025-07-01T18:26:06","slug":"residuos-peligrosos","status":"publish","type":"mec-events","link":"https:\/\/coparmexjal.org.mx\/cpx\/cursos\/residuos-peligrosos\/","title":{"rendered":"Gesti\u00f3n de residuos peligrosos"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Conoce las disposiciones legales, las pol\u00edticas y los procesos de gesti\u00f3n vigentes para el manejo integral de los residuos, su aplicaci\u00f3n y alcances t\u00e9cnicos y jur\u00eddicos, as\u00ed como los principios e instrumentos que los regulan.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfPara qui\u00e9n es este curso?<\/strong><\/p>\n<p>Personal de mantenimiento, seguridad, medioambiente en empresas.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1644542146667{background-color: #f9f9f9 !important;}\u00bb][vc_column][vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text]<b><span style=\"color: #339966;\">Fechas:<\/span><br \/>\n<\/b>26 de julio y 02, 09, 16, 23 de agosto de 2025<br \/>\n<b style=\"color: #339966;\">Duraci\u00f3n:<br \/>\n<\/b>15 horas<br \/>\n<b style=\"color: #339966;\">Horario:<br \/>\n<\/b>9:00 a 12:00 hrs[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text]<b><span style=\"color: #339966;\">Nivel de conocimiento:<\/span><br \/>\n<\/b>No es necesario contar con conocimiento previo.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text]<b><span style=\"color: #339966;\">Habilidades del participante:<\/span><br \/>\n<\/b>-Compromiso<\/p>\n<p><b style=\"color: #339966;\">Requerimientos:<br \/>\n<\/b>-Disposici\u00f3n para aprender[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]<b><span style=\"color: #339966;\">Obtienes:<\/span><br \/>\n<\/b>Diploma, curso pr\u00e1ctico y constancia DC-3[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]<b><span style=\"color: #339966;\">Aprender\u00e1s a:<\/span><br \/>\n<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Comprender el marco normativo aplicable al manejo integral de los residuos en M\u00e9xico<\/li>\n<li aria-level=\"1\">Distinguir las categor\u00edas de residuos y las responsabilidades asociadas a su manejo<\/li>\n<li aria-level=\"1\">Dise\u00f1ar estrategias de gesti\u00f3n de residuos seg\u00fan los niveles de generaci\u00f3n<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_tta_accordion style=\u00bbmodern\u00bb active_section=\u00bb1&#8243; no_fill=\u00bbtrue\u00bb collapsible_all=\u00bbtrue\u00bb title=\u00bbTemario\u00bb][vc_tta_section title=\u00bbM\u00f3dulo I\u00bb tab_id=\u00bb1572040042016-5cce572d-ba10&#8243;][vc_column_text]<\/p>\n<ul>\n<li>Presentaci\u00f3n inicial.<\/li>\n<li>Pol\u00edtica nacional para el manejo integral de los residuos.<\/li>\n<li>El Programa Nacional para la Prevenci\u00f3n y Gesti\u00f3n Integral de los Residuos.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbM\u00f3dulo II\u00bb tab_id=\u00bb1652977524633-abdb3e62-edeb\u00bb][vc_column_text]<\/p>\n<ul>\n<li>Legislaci\u00f3n en materia de residuos.<\/li>\n<li>Las autoridades competentes en M\u00e9xico.<\/li>\n<li>Jurisdicci\u00f3n y competencias.<\/li>\n<li>Normas mexicanas oficiales aplicables.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbM\u00f3dulo III\u00bb tab_id=\u00bb1652977536900-29e8a3ea-caf1&#8243;][vc_column_text]<\/p>\n<ul>\n<li>Gesti\u00f3n p\u00fablica del manejo integral de los residuos.<\/li>\n<li>Clasificaci\u00f3n de los residuos.<\/li>\n<li>Residuos s\u00f3lidos urbanos.<\/li>\n<li>Residuos de manejo especial.<\/li>\n<li>Residuos peligrosos.<\/li>\n<li>Derechos y obligaciones en el manejo integral de los residuos.<\/li>\n<li>Registros, permisos, licencias, autorizaciones y concesiones para el manejo integral de los residuos.<\/li>\n<li>El micro generador.<\/li>\n<li>El peque\u00f1o generador.<\/li>\n<li>El gran generador.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbM\u00f3dulo IV\u00bb tab_id=\u00bb1652977544456-893e2809-1a56&#8243;][vc_column_text]<\/p>\n<ul>\n<li>Gesti\u00f3n privada del manejo integral de los residuos.<\/li>\n<li>Los incentivos para el manejo integral de los residuos.<\/li>\n<li>La acreditaci\u00f3n de la Entidad Mexicana de Acreditaci\u00f3n EMA.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<\/p>\n<p style=\"font-size: 20px;\"><strong style=\"color: #0071ce;\">Socio Coparmex:<\/strong><\/p>\n<p>solicita tu c\u00f3digo promocional y obt\u00e9n <strong style=\"color: #96bd13;\">un descuento adicional <\/strong> en todos los cursos.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_tta_accordion style=\u00bbmodern\u00bb c_icon=\u00bbtriangle\u00bb active_section=\u00bb0&#8243; no_fill=\u00bbtrue\u00bb collapsible_all=\u00bbtrue\u00bb][vc_tta_section title=\u00bbQuiero que me contacte un asesor\u00bb tab_id=\u00bb1592500042006-800fdc9e-0f56&#8243;][dhvc_form id=\u00bb19061&#8243;][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Conoce las disposiciones legales, las pol\u00edticas y los procesos de gesti\u00f3n vigentes para el manejo integral de los residuos, su aplicaci\u00f3n y alcances t\u00e9cnicos y jur\u00eddicos, as\u00ed como los principios e instrumentos que los regulan. \u00bfPara qui\u00e9n es este curso? Personal de mantenimiento, seguridad, medioambiente en empresas.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1644542146667{background-color: #f9f9f9 !important;}\u00bb][vc_column][vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text]Fechas: 26 de julio y &hellip; <\/p>\n","protected":false},"author":1,"featured_media":11657,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[865],"mec_speaker":[933],"class_list":["post-23979","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","mec_category-seguridad-medioambiente"],"_links":{"self":[{"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/mec-events\/23979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/comments?post=23979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/media\/11657"}],"wp:attachment":[{"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/media?parent=23979"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/tags?post=23979"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/mec_category?post=23979"},{"taxonomy":"mec_speaker","embeddable":true,"href":"https:\/\/coparmexjal.org.mx\/cpx\/wp-json\/wp\/v2\/mec_speaker?post=23979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}